{"id":1570,"date":"2021-04-03T10:52:23","date_gmt":"2021-04-03T09:52:23","guid":{"rendered":"https:\/\/semperprodest.hu\/?p=1570"},"modified":"2021-04-03T10:53:46","modified_gmt":"2021-04-03T09:53:46","slug":"valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03","status":"publish","type":"post","link":"https:\/\/semperprodest.hu\/en\/2021\/04\/03\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\/","title":{"rendered":"V\u00e1ltoz\u00e1sok a v\u00e1laszthat\u00f3 e-ker\u00e9kp\u00e1rok \u00e9s keresked\u0151k list\u00e1j\u00e1ban &#8211; 2021.04.03."},"content":{"rendered":"<p>A legfrissebb lista az <a href=\"https:\/\/www.elektromos-kerekpar-palyazat.hu\/e-kerekpar-lista\/e-kerekpar-lista.html\">elektromos-ker\u00e9kp\u00e1r p\u00e1ly\u00e1zat oldalunkon<\/a> el\u00e9rhet\u0151.<\/p>\n<p>A kor\u00e1bbi v\u00e1ltozathoz k\u00e9pest az al\u00e1bbi m\u00f3dos\u00edt\u00e1sok t\u00f6rt\u00e9ntek:<br \/>\n<i>(Jelz\u00e9sek: \u00c1th\u00fazott r\u00f3zsasz\u00edn h\u00e1tt\u00e9r &#8211; t\u00f6r\u00f6lt\u00e9k. Z\u00f6ld h\u00e1tt\u00e9r &#8211; \u00faj sz\u00f6vegr\u00e9szek.)<\/i><\/p>\n<ul class=\"b\">\n<li style=\"list-style-type: none;\">\n<ul class=\"b\">\n<li>CTM Senze Man Trek t\u00faratrekking<\/li>\n<li>Cube Touring Hybrid One 500<\/li>\n<li><span class=\"added\">Cube Touring Hybrid One 500 unisex<\/span><\/li>\n<li><span class=\"added\"><\/span>Gepida Alboin 28&#8243; LALF8<\/li>\n<li>Gepida Alboin Curve 28&#8243; L10S<\/li>\n<li>Gepida Asgard 1000 PS 27,5 Di2 fekete-k\u00e9k<\/li>\n<hr>\n<li>Gepida Reptila 1000 28&#8243; W 8 SR<\/li>\n<li>Gepida Ruga Pro 27,5&#8243; M10S INT<\/li>\n<li><span class=\"removed\">Neuzer Como E-Trekking<\/span><\/li>\n<li><span class=\"removed\"><\/span>Neuzer E-Trekking f\u00e9rfi Zagon 21&#8242;<\/li>\n<li>Neuzer Hollandia Optima Basic 7 SPD Alu<\/li>\n<hr>\n<li>Neuzer Hollandia Optima Basic 7 SPD Alu<\/li>\n<li><span class=\"removed\">Neuzer Lido F\u00e9rfi<\/span><\/li>\n<li><span class=\"removed\"><\/span>Neuzer Lido N\u0151i<\/li>\n<li>Neuzer Menton N\u0151i 18<\/li>\n<li>Neuzer Siena 17 Bafang k\u00f6z\u00e9pmotoros<\/li>\n<hr>\n<li>Neuzer Menton N\u0151i 18<\/li>\n<li>Neuzer Siena 17 Bafang k\u00f6z\u00e9pmotoros<\/li>\n<li><span class=\"removed\">Neuzer Zagon E-Trekking (Shengyi motor) n\u0151i<\/span><\/li>\n<li><span class=\"removed\"><\/span>Elektro Bike Kereskedelmi Korl\u00e1tolt Felel\u0151ss\u00e9g\u0171 T\u00e1rsas\u00e1g<\/li>\n<li>\u00dczlet neve:<b> Elektromos Ker\u00e9kp\u00e1r Gal\u00e9ria<\/b><\/li>\n<li>Sz\u00e9khely c\u00edme: 2700 Cegl\u00e9d V\u00e1rkonyi Istv\u00e1n utca 49<\/li>\n<hr>\n<li>NEUZER Lido teleszk\u00f3kpos f\u00e9rfi<\/li>\n<li>NEUZER Lido teleszk\u00f3pos n\u0151i<\/li>\n<li><span class=\"added\">NEUZER Zagon Shengyi n\u0151i teleszk\u00f3pos vill\u00e1val 6seb.<\/span><\/li>\n<li><span class=\"added\"><\/span>PED\u00c1LLUS Kereskedelmi \u00e9s Szolg\u00e1ltat\u00f3 Korl\u00e1tolt Felel\u0151ss\u00e9g\u0171 T\u00e1rsas\u00e1g<\/li>\n<li>\u00dczlet neve:<b> Ker\u00e9kP\u00e1ros<\/b><\/li>\n<li>Sz\u00e9khely c\u00edme: 1094 Budapest, Ferenc t\u00e9r 9.<\/li>\n<hr>\n<li>Dema E-Silence<\/li>\n<li>Giant DailyTour E+<\/li>\n<li><span class=\"removed\">Giant Explore E+ 2 STA n\u0151i (2021)<\/span><\/li>\n<li><span class=\"removed\"><\/span>Giant Explore E+ 3 GTS f\u00e9rfi (2021)<\/li>\n<li>Giant Explore E+ 3 GTS n\u0151i (2021)<\/li>\n<hr>\n<li>Giant Explore E+ 3 GTS n\u0151i (2021)<\/li>\n<li><span class=\"removed\">Giant Explore E+2 GTS f\u00e9rfi (2021)<\/span><\/li>\n<li><span class=\"removed\">Giant Explore E+3 STA n\u0151i (2021)<\/span><\/li>\n<li><span class=\"removed\"><\/span>Giant Roam E+ GTS (f\u00e9rfi) (2021)<\/li>\n<li>Giant Roam E+ STA (n\u0151i) (2021)<\/li>\n<li>Hercules E-Joy F7<\/li>\n<hr>\n<li>Hercules Montfoort F7 n\u0151i<\/li>\n<li>Hercules Nizza F7 NL n\u0151i<\/li>\n<li><span class=\"removed\">Hercules Rob Fold F8<\/span><\/li>\n<li><span class=\"removed\">Hercules Rob Fold R7<\/span><\/li>\n<li><span class=\"removed\"><\/span>Hercules Robert\/a Deluxe I-F8<\/li>\n<li>Hercules Robert\/a Deluxe I-R8<\/li>\n<li>Hercules Robert\/a F7 Active Plus<\/li>\n<hr>\n<li>Kenzel E-Dream Classic (26&#8243;)<\/li>\n<li>Kenzel E-Dream Classic (28&#8243;)<\/li>\n<li>Kenzel E-XONIC CROSS<span class=\"removed\"><\/span><\/li>\n<li><span class=\"removed\">LIV Rove E+ (2021)<\/span><span class=\"added\">Kenzel E-XONIC CROSS<\/span><\/li>\n<li>Neuzer Hollandia Basic Alu n\u0151i<\/li>\n<li>Neuzer Hollandia Basic n\u0151i ac\u00e9l 19<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>A legfrissebb lista az elektromos-ker\u00e9kp\u00e1r p\u00e1ly\u00e1zat oldalunkon el\u00e9rhet\u0151. A kor\u00e1bbi v\u00e1ltozathoz k\u00e9pest az al\u00e1bbi m\u00f3dos\u00edt\u00e1sok t\u00f6rt\u00e9ntek: (Jelz\u00e9sek: \u00c1th\u00fazott r\u00f3zsasz\u00edn h\u00e1tt\u00e9r &#8211; t\u00f6r\u00f6lt\u00e9k. Z\u00f6ld h\u00e1tt\u00e9r &#8211; \u00faj sz\u00f6vegr\u00e9szek.) CTM Senze Man Trek t\u00faratrekking Cube Touring Hybrid One 500 Cube Touring Hybrid One 500 unisex Gepida Alboin 28&#8243; LALF8 Gepida Alboin Curve 28&#8243; L10S Gepida Asgard 1000 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1571,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[19,18],"tags":[37,38],"class_list":["post-1570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-elektromos-kerekpar-palyazat","category-palyazatok","tag-kerekpar-lista","tag-kereskedo-lista"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>V\u00e1ltoz\u00e1sok a v\u00e1laszthat\u00f3 e-ker\u00e9kp\u00e1rok \u00e9s keresked\u0151k list\u00e1j\u00e1ban - 2021.04.03. &#8902; Semper Prodest Kft.<\/title>\n<meta name=\"description\" content=\"Az elektromos ker\u00e9kp\u00e1r \u00e9s keresked\u0151 list\u00e1j\u00e1ban t\u00f6rt\u00e9nt v\u00e1ltoz\u00e1sok 2021.04.03.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/semperprodest.hu\/en\/2021\/04\/03\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"V\u00e1ltoz\u00e1sok a v\u00e1laszthat\u00f3 e-ker\u00e9kp\u00e1rok \u00e9s keresked\u0151k list\u00e1j\u00e1ban - 2021.04.03. &#8902; Semper Prodest Kft.\" \/>\n<meta property=\"og:description\" content=\"Az elektromos ker\u00e9kp\u00e1r \u00e9s keresked\u0151 list\u00e1j\u00e1ban t\u00f6rt\u00e9nt v\u00e1ltoz\u00e1sok 2021.04.03.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/semperprodest.hu\/en\/2021\/04\/03\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\/\" \/>\n<meta property=\"og:site_name\" content=\"Semper Prodest Kft.\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-03T09:52:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-03T09:53:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/semperprodest.hu\/wp-content\/uploads\/2021\/04\/e-bike-palyazat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1210\" \/>\n\t<meta property=\"og:image:height\" content=\"423\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"csernatig\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"csernatig\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/semperprodest.hu\\\/2021\\\/04\\\/03\\\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semperprodest.hu\\\/2021\\\/04\\\/03\\\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\\\/\"},\"author\":{\"name\":\"csernatig\",\"@id\":\"https:\\\/\\\/semperprodest.hu\\\/#\\\/schema\\\/person\\\/26e392c57385f3f8331ca59302c57044\"},\"headline\":\"V\u00e1ltoz\u00e1sok a v\u00e1laszthat\u00f3 e-ker\u00e9kp\u00e1rok \u00e9s keresked\u0151k list\u00e1j\u00e1ban &#8211; 2021.04.03.\",\"datePublished\":\"2021-04-03T09:52:23+00:00\",\"dateModified\":\"2021-04-03T09:53:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/semperprodest.hu\\\/2021\\\/04\\\/03\\\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\\\/\"},\"wordCount\":363,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/semperprodest.hu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/semperprodest.hu\\\/2021\\\/04\\\/03\\\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semperprodest.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/e-bike-palyazat.jpg\",\"keywords\":[\"ker\u00e9kp\u00e1r lista\",\"keresked\u0151 lista\"],\"articleSection\":[\"Elektromos ker\u00e9kp\u00e1r p\u00e1ly\u00e1zat\",\"P\u00e1ly\u00e1zatok\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/semperprodest.hu\\\/2021\\\/04\\\/03\\\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/semperprodest.hu\\\/2021\\\/04\\\/03\\\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\\\/\",\"url\":\"https:\\\/\\\/semperprodest.hu\\\/2021\\\/04\\\/03\\\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\\\/\",\"name\":\"V\u00e1ltoz\u00e1sok a v\u00e1laszthat\u00f3 e-ker\u00e9kp\u00e1rok \u00e9s keresked\u0151k list\u00e1j\u00e1ban - 2021.04.03. &#8902; Semper Prodest Kft.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/semperprodest.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/semperprodest.hu\\\/2021\\\/04\\\/03\\\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/semperprodest.hu\\\/2021\\\/04\\\/03\\\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/semperprodest.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/e-bike-palyazat.jpg\",\"datePublished\":\"2021-04-03T09:52:23+00:00\",\"dateModified\":\"2021-04-03T09:53:46+00:00\",\"description\":\"Az elektromos ker\u00e9kp\u00e1r \u00e9s keresked\u0151 list\u00e1j\u00e1ban t\u00f6rt\u00e9nt v\u00e1ltoz\u00e1sok 2021.04.03.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/semperprodest.hu\\\/2021\\\/04\\\/03\\\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/semperprodest.hu\\\/2021\\\/04\\\/03\\\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/semperprodest.hu\\\/2021\\\/04\\\/03\\\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\\\/#primaryimage\",\"url\":\"https:\\\/\\\/semperprodest.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/e-bike-palyazat.jpg\",\"contentUrl\":\"https:\\\/\\\/semperprodest.hu\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/e-bike-palyazat.jpg\",\"width\":1210,\"height\":423,\"caption\":\"pedelec p\u00e1ly\u00e1zat \u00e9s t\u00e1mogat\u00e1s\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/semperprodest.hu\\\/2021\\\/04\\\/03\\\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Kezd\u0151lap\",\"item\":\"https:\\\/\\\/semperprodest.hu\\\/fooldal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00e1ltoz\u00e1sok a v\u00e1laszthat\u00f3 e-ker\u00e9kp\u00e1rok \u00e9s keresked\u0151k list\u00e1j\u00e1ban &#8211; 2021.04.03.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/semperprodest.hu\\\/#website\",\"url\":\"https:\\\/\\\/semperprodest.hu\\\/\",\"name\":\"Semper Prodest Kft.\",\"description\":\"P\u00e1ly\u00e1zat, informatika\",\"publisher\":{\"@id\":\"https:\\\/\\\/semperprodest.hu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/semperprodest.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/semperprodest.hu\\\/#organization\",\"name\":\"Semper Prodest Kft.\",\"url\":\"https:\\\/\\\/semperprodest.hu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/semperprodest.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/semperprodest.hu\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/semper-prodest-logo.png\",\"contentUrl\":\"https:\\\/\\\/semperprodest.hu\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/semper-prodest-logo.png\",\"width\":340,\"height\":156,\"caption\":\"Semper Prodest Kft.\"},\"image\":{\"@id\":\"https:\\\/\\\/semperprodest.hu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/semperprodest.hu\\\/#\\\/schema\\\/person\\\/26e392c57385f3f8331ca59302c57044\",\"name\":\"csernatig\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/semperprodest.hu\\\/wp-content\\\/litespeed\\\/avatar\\\/a1e43e41a75896b4436b104924275e67.jpg?ver=1783572486\",\"url\":\"https:\\\/\\\/semperprodest.hu\\\/wp-content\\\/litespeed\\\/avatar\\\/a1e43e41a75896b4436b104924275e67.jpg?ver=1783572486\",\"contentUrl\":\"https:\\\/\\\/semperprodest.hu\\\/wp-content\\\/litespeed\\\/avatar\\\/a1e43e41a75896b4436b104924275e67.jpg?ver=1783572486\",\"caption\":\"csernatig\"},\"sameAs\":[\"http:\\\/\\\/semperprodest.hu\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"V\u00e1ltoz\u00e1sok a v\u00e1laszthat\u00f3 e-ker\u00e9kp\u00e1rok \u00e9s keresked\u0151k list\u00e1j\u00e1ban - 2021.04.03. &#8902; Semper Prodest Kft.","description":"Az elektromos ker\u00e9kp\u00e1r \u00e9s keresked\u0151 list\u00e1j\u00e1ban t\u00f6rt\u00e9nt v\u00e1ltoz\u00e1sok 2021.04.03.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/semperprodest.hu\/en\/2021\/04\/03\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\/","og_locale":"en_US","og_type":"article","og_title":"V\u00e1ltoz\u00e1sok a v\u00e1laszthat\u00f3 e-ker\u00e9kp\u00e1rok \u00e9s keresked\u0151k list\u00e1j\u00e1ban - 2021.04.03. &#8902; Semper Prodest Kft.","og_description":"Az elektromos ker\u00e9kp\u00e1r \u00e9s keresked\u0151 list\u00e1j\u00e1ban t\u00f6rt\u00e9nt v\u00e1ltoz\u00e1sok 2021.04.03.","og_url":"https:\/\/semperprodest.hu\/en\/2021\/04\/03\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\/","og_site_name":"Semper Prodest Kft.","article_published_time":"2021-04-03T09:52:23+00:00","article_modified_time":"2021-04-03T09:53:46+00:00","og_image":[{"width":1210,"height":423,"url":"https:\/\/semperprodest.hu\/wp-content\/uploads\/2021\/04\/e-bike-palyazat.jpg","type":"image\/jpeg"}],"author":"csernatig","twitter_card":"summary_large_image","twitter_misc":{"Written by":"csernatig","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/semperprodest.hu\/2021\/04\/03\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\/#article","isPartOf":{"@id":"https:\/\/semperprodest.hu\/2021\/04\/03\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\/"},"author":{"name":"csernatig","@id":"https:\/\/semperprodest.hu\/#\/schema\/person\/26e392c57385f3f8331ca59302c57044"},"headline":"V\u00e1ltoz\u00e1sok a v\u00e1laszthat\u00f3 e-ker\u00e9kp\u00e1rok \u00e9s keresked\u0151k list\u00e1j\u00e1ban &#8211; 2021.04.03.","datePublished":"2021-04-03T09:52:23+00:00","dateModified":"2021-04-03T09:53:46+00:00","mainEntityOfPage":{"@id":"https:\/\/semperprodest.hu\/2021\/04\/03\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\/"},"wordCount":363,"commentCount":0,"publisher":{"@id":"https:\/\/semperprodest.hu\/#organization"},"image":{"@id":"https:\/\/semperprodest.hu\/2021\/04\/03\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\/#primaryimage"},"thumbnailUrl":"https:\/\/semperprodest.hu\/wp-content\/uploads\/2021\/04\/e-bike-palyazat.jpg","keywords":["ker\u00e9kp\u00e1r lista","keresked\u0151 lista"],"articleSection":["Elektromos ker\u00e9kp\u00e1r p\u00e1ly\u00e1zat","P\u00e1ly\u00e1zatok"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/semperprodest.hu\/2021\/04\/03\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/semperprodest.hu\/2021\/04\/03\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\/","url":"https:\/\/semperprodest.hu\/2021\/04\/03\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\/","name":"V\u00e1ltoz\u00e1sok a v\u00e1laszthat\u00f3 e-ker\u00e9kp\u00e1rok \u00e9s keresked\u0151k list\u00e1j\u00e1ban - 2021.04.03. &#8902; Semper Prodest Kft.","isPartOf":{"@id":"https:\/\/semperprodest.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/semperprodest.hu\/2021\/04\/03\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\/#primaryimage"},"image":{"@id":"https:\/\/semperprodest.hu\/2021\/04\/03\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\/#primaryimage"},"thumbnailUrl":"https:\/\/semperprodest.hu\/wp-content\/uploads\/2021\/04\/e-bike-palyazat.jpg","datePublished":"2021-04-03T09:52:23+00:00","dateModified":"2021-04-03T09:53:46+00:00","description":"Az elektromos ker\u00e9kp\u00e1r \u00e9s keresked\u0151 list\u00e1j\u00e1ban t\u00f6rt\u00e9nt v\u00e1ltoz\u00e1sok 2021.04.03.","breadcrumb":{"@id":"https:\/\/semperprodest.hu\/2021\/04\/03\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/semperprodest.hu\/2021\/04\/03\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/semperprodest.hu\/2021\/04\/03\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\/#primaryimage","url":"https:\/\/semperprodest.hu\/wp-content\/uploads\/2021\/04\/e-bike-palyazat.jpg","contentUrl":"https:\/\/semperprodest.hu\/wp-content\/uploads\/2021\/04\/e-bike-palyazat.jpg","width":1210,"height":423,"caption":"pedelec p\u00e1ly\u00e1zat \u00e9s t\u00e1mogat\u00e1s"},{"@type":"BreadcrumbList","@id":"https:\/\/semperprodest.hu\/2021\/04\/03\/valtozasok-a-valaszthato-e-kerekparok-es-kereskedok-listajaban-2021-04-03\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Kezd\u0151lap","item":"https:\/\/semperprodest.hu\/fooldal\/"},{"@type":"ListItem","position":2,"name":"V\u00e1ltoz\u00e1sok a v\u00e1laszthat\u00f3 e-ker\u00e9kp\u00e1rok \u00e9s keresked\u0151k list\u00e1j\u00e1ban &#8211; 2021.04.03."}]},{"@type":"WebSite","@id":"https:\/\/semperprodest.hu\/#website","url":"https:\/\/semperprodest.hu\/","name":"Semper Prodest Ltd.","description":"P\u00e1ly\u00e1zat, informatika","publisher":{"@id":"https:\/\/semperprodest.hu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/semperprodest.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/semperprodest.hu\/#organization","name":"Semper Prodest Ltd.","url":"https:\/\/semperprodest.hu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/semperprodest.hu\/#\/schema\/logo\/image\/","url":"https:\/\/semperprodest.hu\/wp-content\/uploads\/2020\/10\/semper-prodest-logo.png","contentUrl":"https:\/\/semperprodest.hu\/wp-content\/uploads\/2020\/10\/semper-prodest-logo.png","width":340,"height":156,"caption":"Semper Prodest Kft."},"image":{"@id":"https:\/\/semperprodest.hu\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/semperprodest.hu\/#\/schema\/person\/26e392c57385f3f8331ca59302c57044","name":"csernatig","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/semperprodest.hu\/wp-content\/litespeed\/avatar\/a1e43e41a75896b4436b104924275e67.jpg?ver=1783572486","url":"https:\/\/semperprodest.hu\/wp-content\/litespeed\/avatar\/a1e43e41a75896b4436b104924275e67.jpg?ver=1783572486","contentUrl":"https:\/\/semperprodest.hu\/wp-content\/litespeed\/avatar\/a1e43e41a75896b4436b104924275e67.jpg?ver=1783572486","caption":"csernatig"},"sameAs":["http:\/\/semperprodest.hu"]}]}},"jetpack_featured_media_url":"https:\/\/semperprodest.hu\/wp-content\/uploads\/2021\/04\/e-bike-palyazat.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/semperprodest.hu\/en\/wp-json\/wp\/v2\/posts\/1570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/semperprodest.hu\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/semperprodest.hu\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/semperprodest.hu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/semperprodest.hu\/en\/wp-json\/wp\/v2\/comments?post=1570"}],"version-history":[{"count":3,"href":"https:\/\/semperprodest.hu\/en\/wp-json\/wp\/v2\/posts\/1570\/revisions"}],"predecessor-version":[{"id":1574,"href":"https:\/\/semperprodest.hu\/en\/wp-json\/wp\/v2\/posts\/1570\/revisions\/1574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/semperprodest.hu\/en\/wp-json\/wp\/v2\/media\/1571"}],"wp:attachment":[{"href":"https:\/\/semperprodest.hu\/en\/wp-json\/wp\/v2\/media?parent=1570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/semperprodest.hu\/en\/wp-json\/wp\/v2\/categories?post=1570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/semperprodest.hu\/en\/wp-json\/wp\/v2\/tags?post=1570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}